{"id":22,"date":"2024-07-30T15:46:29","date_gmt":"2024-07-30T13:46:29","guid":{"rendered":"https:\/\/simecongress.com\/?page_id=22"},"modified":"2025-07-17T17:15:33","modified_gmt":"2025-07-17T15:15:33","slug":"temi-congressuali","status":"publish","type":"page","link":"https:\/\/simecongress.com\/it\/46-congresso-sime\/temi-congressuali\/","title":{"rendered":"Temi Congressuali"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row row_height_percent=&#8221;0&#8243; override_padding=&#8221;yes&#8221; h_padding=&#8221;2&#8243; top_padding=&#8221;3&#8243; bottom_padding=&#8221;2&#8243; overlay_alpha=&#8221;50&#8243; gutter_size=&#8221;3&#8243; column_width_percent=&#8221;100&#8243; shift_y=&#8221;0&#8243; z_index=&#8221;0&#8243; desktop_visibility=&#8221;yes&#8221; medium_visibility=&#8221;yes&#8221; mobile_visibility=&#8221;yes&#8221; uncode_shortcode_id=&#8221;330978&#8243;][vc_column width=&#8221;1\/3&#8243;][vc_button button_color=&#8221;color-161507&#8243; size=&#8221;btn-lg&#8221; radius=&#8221;btn-circle&#8221; border_animation=&#8221;btn-ripple-out&#8221; wide=&#8221;yes&#8221; custom_typo=&#8221;yes&#8221; font_family=&#8221;font-555555&#8243; font_weight=&#8221;800&#8243; border_width=&#8221;0&#8243; link=&#8221;url:%23&#8243; button_color_type=&#8221;uncode-palette&#8221; uncode_shortcode_id=&#8221;203815&#8243;]SINOSSI SCIENTIFICA PDF[\/vc_button][\/vc_column][vc_column width=&#8221;1\/3&#8243;][vc_button button_color=&#8221;color-161507&#8243; size=&#8221;btn-lg&#8221; radius=&#8221;btn-circle&#8221; border_animation=&#8221;btn-ripple-out&#8221; wide=&#8221;yes&#8221; custom_typo=&#8221;yes&#8221; font_family=&#8221;font-555555&#8243; font_weight=&#8221;800&#8243; border_width=&#8221;0&#8243; link=&#8221;url:%23&#8243; button_color_type=&#8221;uncode-palette&#8221; uncode_shortcode_id=&#8221;110727&#8243;]SINOSSI SCIENTIFICA INTERATTIVA[\/vc_button][\/vc_column][vc_column width=&#8221;1\/3&#8243;][vc_button button_color=&#8221;color-161507&#8243; size=&#8221;btn-lg&#8221; radius=&#8221;btn-circle&#8221; border_animation=&#8221;btn-ripple-out&#8221; wide=&#8221;yes&#8221; custom_typo=&#8221;yes&#8221; font_family=&#8221;font-555555&#8243; font_weight=&#8221;800&#8243; border_width=&#8221;0&#8243; link=&#8221;url:%23&#8243; button_color_type=&#8221;uncode-palette&#8221; uncode_shortcode_id=&#8221;180928&#8243;]PROGRAMMA SCIENTIFICO[\/vc_button][\/vc_column][\/vc_row][vc_row row_height_percent=&#8221;0&#8243; override_padding=&#8221;yes&#8221; h_padding=&#8221;2&#8243; top_padding=&#8221;2&#8243; bottom_padding=&#8221;2&#8243; overlay_alpha=&#8221;50&#8243; gutter_size=&#8221;0&#8243; column_width_percent=&#8221;100&#8243; shift_y=&#8221;0&#8243; z_index=&#8221;0&#8243; uncode_shortcode_id=&#8221;101138&#8243;][vc_column column_width_percent=&#8221;100&#8243; align_horizontal=&#8221;align_center&#8221; gutter_size=&#8221;3&#8243; override_padding=&#8221;yes&#8221; column_padding=&#8221;0&#8243; overlay_alpha=&#8221;50&#8243; border_color=&#8221;color-nhtu&#8221; border_style=&#8221;solid&#8221; shift_x=&#8221;0&#8243; shift_y=&#8221;0&#8243; shift_y_down=&#8221;0&#8243; z_index=&#8221;0&#8243; medium_width=&#8221;0&#8243; mobile_width=&#8221;0&#8243; width=&#8221;1\/2&#8243; uncode_shortcode_id=&#8221;428490&#8243; el_class=&#8221;elemento-no-cliccato&#8221; css=&#8221;.vc_custom_1752136533701{border-bottom-width: 1px !important;}&#8221; border_color_type=&#8221;uncode-palette&#8221; link_to=&#8221;url:https%3A%2F%2Fsimecongress.com%2Fit%2F46-congresso-sime%2Fcomitato-scientifico%2F|title:Comitato%20Scientifico&#8221;][vc_custom_heading text_color=&#8221;color-gyho&#8221; heading_semantic=&#8221;div&#8221; text_size=&#8221;h3&#8243; text_weight=&#8221;400&#8243; uncode_shortcode_id=&#8221;612023&#8243; text_color_type=&#8221;uncode-palette&#8221;]COMITATO SCIENTIFICO[\/vc_custom_heading][\/vc_column][vc_column column_width_percent=&#8221;100&#8243; align_horizontal=&#8221;align_center&#8221; gutter_size=&#8221;3&#8243; override_padding=&#8221;yes&#8221; column_padding=&#8221;0&#8243; overlay_alpha=&#8221;50&#8243; border_color=&#8221;color-nhtu&#8221; border_style=&#8221;solid&#8221; shift_x=&#8221;0&#8243; shift_y=&#8221;0&#8243; shift_y_down=&#8221;0&#8243; z_index=&#8221;0&#8243; medium_width=&#8221;0&#8243; mobile_width=&#8221;0&#8243; width=&#8221;1\/2&#8243; uncode_shortcode_id=&#8221;983053&#8243; el_class=&#8221;elemento-cliccato&#8221; link_to=&#8221;url:https%3A%2F%2Fsimecongress.com%2Fit%2F46-congresso-sime%2Ftemi-congressuali%2F|title:Patrocini%20e%20Collaborazioni&#8221; css=&#8221;.vc_custom_1752136546396{border-bottom-width: 1px !important;}&#8221; border_color_type=&#8221;uncode-palette&#8221;][vc_custom_heading heading_semantic=&#8221;h1&#8243; text_size=&#8221;h3&#8243; uncode_shortcode_id=&#8221;767143&#8243;]TEMI CONGRESSUALI[\/vc_custom_heading][\/vc_column][\/vc_row][vc_row row_height_percent=&#8221;0&#8243; override_padding=&#8221;yes&#8221; h_padding=&#8221;2&#8243; top_padding=&#8221;2&#8243; bottom_padding=&#8221;2&#8243; overlay_alpha=&#8221;50&#8243; gutter_size=&#8221;0&#8243; column_width_percent=&#8221;100&#8243; shift_y=&#8221;0&#8243; z_index=&#8221;0&#8243; uncode_shortcode_id=&#8221;950242&#8243; el_class=&#8221;colonna-temi-congressuali&#8221;][vc_column column_width_percent=&#8221;100&#8243; gutter_size=&#8221;3&#8243; override_padding=&#8221;yes&#8221; column_padding=&#8221;3&#8243; overlay_alpha=&#8221;50&#8243; border_color=&#8221;color-nhtu&#8221; border_style=&#8221;solid&#8221; shift_x=&#8221;0&#8243; shift_y=&#8221;0&#8243; shift_y_down=&#8221;0&#8243; z_index=&#8221;0&#8243; medium_width=&#8221;0&#8243; mobile_width=&#8221;0&#8243; width=&#8221;1\/2&#8243; uncode_shortcode_id=&#8221;142560&#8243; css=&#8221;.vc_custom_1724751470386{border-right-width: 1px !important;border-left-width: 1px !important;}&#8221; border_color_type=&#8221;uncode-palette&#8221;][vc_column_text text_lead=&#8221;small&#8221; uncode_shortcode_id=&#8221;214716&#8243;]<\/p>\n<ul>\n<li>Acne: approccio integrato<\/li>\n<li>Anatomia funzionale ed ecografia in Medicina Estetica<\/li>\n<li>Biostimolazione e Bioristrutturazione<\/li>\n<li>Case report: esperienze cliniche<\/li>\n<li>Chirurgia Plastica Estetica<\/li>\n<li>Complicanze in Medicina Estetica<\/li>\n<li>Cosmetologia: aggiornamenti e novit\u00e0<\/li>\n<li>Dermatologia di competenza medico-estetica<\/li>\n<li>Filler: dalla bioristrutturazione alla biovolumetria<\/li>\n<li>Flebologia medica e chirurgica<\/li>\n<li>Geroscienza in Medicina Estetica<\/li>\n<li>Ginecologia Estetica e Funzionale<\/li>\n<li>Iperpigmentazioni e melasma: aggiornamenti terapeutici<\/li>\n<li>Laser e Energy-based Devices in Medicina Estetica<\/li>\n<li>Lifting non chirurgico: dai fili alle nuove tecnologie<\/li>\n<li>Mani e piedi: up to date in Medicina Estetica<\/li>\n<li>Marketing e Medicina Estetica<\/li>\n<li>Medicina Estetica<\/li>\n<\/ul>\n<p>[\/vc_column_text][\/vc_column][vc_column column_width_percent=&#8221;100&#8243; gutter_size=&#8221;3&#8243; override_padding=&#8221;yes&#8221; column_padding=&#8221;3&#8243; overlay_alpha=&#8221;50&#8243; border_color=&#8221;color-nhtu&#8221; border_style=&#8221;solid&#8221; shift_x=&#8221;0&#8243; shift_y=&#8221;0&#8243; shift_y_down=&#8221;0&#8243; z_index=&#8221;0&#8243; medium_width=&#8221;0&#8243; mobile_width=&#8221;0&#8243; width=&#8221;1\/2&#8243; uncode_shortcode_id=&#8221;235085&#8243; css=&#8221;.vc_custom_1724751477456{border-right-width: 1px !important;}&#8221; border_color_type=&#8221;uncode-palette&#8221;][vc_column_text text_lead=&#8221;small&#8221; uncode_shortcode_id=&#8221;127845&#8243;]<\/p>\n<ul>\n<li>Medicina Estetica e Agopuntura<\/li>\n<li>Medicina Estetica Ricostruttiva<\/li>\n<li>Medicina Estetica in Oncologia<\/li>\n<li>Medicina Rigenerativa e PRP<\/li>\n<li>Mesoterapia in Medicina Estetica<\/li>\n<li>Neuromodulazione e Miomodulazione<\/li>\n<li>Nuove proposte in Medicina Estetica<\/li>\n<li>Nutrizione, obesit\u00e0 e DCA<\/li>\n<li>Omeopatia e omotossicologia in Medicina Estetica<\/li>\n<li>Peeling: nuovi orientamenti, nuove formulazioni<\/li>\n<li>PEFS e AL<\/li>\n<li>Prevenzione e monitoraggio dell&#8217;Aging in Medicina Estetica<\/li>\n<li>Protocolli combinati in Medicina Estetica<\/li>\n<li>Rinoplastica Medica<\/li>\n<li>Tatuaggi: rischi, sicurezza e cura<\/li>\n<li>Tossina Botulinica: novit\u00e0 e conferme sulla farmacodinamica<\/li>\n<li>Tricologia: up to date<\/li>\n<\/ul>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row row_height_percent=&#8221;0&#8243; override_padding=&#8221;yes&#8221; h_padding=&#8221;0&#8243; top_padding=&#8221;2&#8243; bottom_padding=&#8221;3&#8243; overlay_alpha=&#8221;50&#8243; gutter_size=&#8221;3&#8243; column_width_percent=&#8221;100&#8243; shift_y=&#8221;0&#8243; z_index=&#8221;0&#8243; uncode_shortcode_id=&#8221;257518&#8243;][vc_column width=&#8221;1\/1&#8243;][vc_button button_color=&#8221;color-161507&#8243; size=&#8221;btn-lg&#8221; radius=&#8221;btn-circle&#8221; border_animation=&#8221;btn-ripple-out&#8221; wide=&#8221;yes&#8221; custom_typo=&#8221;yes&#8221; font_family=&#8221;font-555555&#8243; font_weight=&#8221;800&#8243; border_width=&#8221;2&#8243; scale_mobile=&#8221;no&#8221; link=&#8221;url:https%3A%2F%2Fsimecongress.com%2F46-congresso-sime%2Fcall-for-abstract%2F|title:Call%20for%20Abstract&#8221; button_color_type=&#8221;uncode-palette&#8221; uncode_shortcode_id=&#8221;191996&#8243; el_class=&#8221;big-text-font&#8221;]INVIA IL TUO ABSTRACT[\/vc_button][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row row_height_percent=&#8221;0&#8243; override_padding=&#8221;yes&#8221; h_padding=&#8221;2&#8243; top_padding=&#8221;3&#8243; bottom_padding=&#8221;2&#8243; overlay_alpha=&#8221;50&#8243; gutter_size=&#8221;3&#8243; column_width_percent=&#8221;100&#8243; shift_y=&#8221;0&#8243; z_index=&#8221;0&#8243; desktop_visibility=&#8221;yes&#8221; medium_visibility=&#8221;yes&#8221; mobile_visibility=&#8221;yes&#8221; uncode_shortcode_id=&#8221;330978&#8243;][vc_column width=&#8221;1\/3&#8243;][vc_button button_color=&#8221;color-161507&#8243; size=&#8221;btn-lg&#8221; radius=&#8221;btn-circle&#8221; border_animation=&#8221;btn-ripple-out&#8221; [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":1257,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-22","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/simecongress.com\/it\/wp-json\/wp\/v2\/pages\/22","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/simecongress.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/simecongress.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/simecongress.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/simecongress.com\/it\/wp-json\/wp\/v2\/comments?post=22"}],"version-history":[{"count":16,"href":"https:\/\/simecongress.com\/it\/wp-json\/wp\/v2\/pages\/22\/revisions"}],"predecessor-version":[{"id":17981,"href":"https:\/\/simecongress.com\/it\/wp-json\/wp\/v2\/pages\/22\/revisions\/17981"}],"up":[{"embeddable":true,"href":"https:\/\/simecongress.com\/it\/wp-json\/wp\/v2\/pages\/1257"}],"wp:attachment":[{"href":"https:\/\/simecongress.com\/it\/wp-json\/wp\/v2\/media?parent=22"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}